{"id":3579,"date":"2024-07-22T07:09:12","date_gmt":"2024-07-22T05:09:12","guid":{"rendered":"https:\/\/davidhorn.com\/resource-hub\/beyond-a-reasonable-doubt-episode-03\/"},"modified":"2025-11-25T14:09:31","modified_gmt":"2025-11-25T13:09:31","slug":"beyond-a-reasonable-doubt-episode-03","status":"publish","type":"resource-hub","link":"https:\/\/davidhorn.com\/fr\/resource-hub\/beyond-a-reasonable-doubt-episode-03\/","title":{"rendered":"Interviews d&rsquo;investigation Emily Alison &#8211; ep.03"},"content":{"rendered":"\n<section class=\"wp-block-group has-primary-25-background-color has-background has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:var(--wp--preset--spacing--80);padding-top:var(--wp--preset--spacing--30);padding-bottom:var(--wp--preset--spacing--30)\">\n<div class=\"wp-block-columns alignwide are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-658170e2 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40%\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/d3pwq9e4hibwhv.cloudfront.net\/wp-content\/uploads\/2024\/07\/15110705\/BaRD_ep03_cover-1024x1024.jpg\" alt=\"\" class=\"wp-image-2755\" style=\"width:472px;height:auto\" srcset=\"https:\/\/d3pwq9e4hibwhv.cloudfront.net\/wp-content\/uploads\/2024\/07\/15110705\/BaRD_ep03_cover-1024x1024.jpg 1024w, https:\/\/d3pwq9e4hibwhv.cloudfront.net\/wp-content\/uploads\/2024\/07\/15110705\/BaRD_ep03_cover-300x300.jpg 300w, https:\/\/d3pwq9e4hibwhv.cloudfront.net\/wp-content\/uploads\/2024\/07\/15110705\/BaRD_ep03_cover-150x150.jpg 150w, https:\/\/d3pwq9e4hibwhv.cloudfront.net\/wp-content\/uploads\/2024\/07\/15110705\/BaRD_ep03_cover-768x768.jpg 768w, https:\/\/d3pwq9e4hibwhv.cloudfront.net\/wp-content\/uploads\/2024\/07\/15110705\/BaRD_ep03_cover.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h1 class=\"wp-block-heading has-display-small-font-size\" id=\"h-episode-03-nous-sommes-a-un-point-de-bascule-dans-les-pratiques-d-interrogatoire-expert-en-interviews-d-investigation-emily-alison\" style=\"line-height:1.2\">\u00c9pisode 03.<br>Nous sommes \u00e0 un point de bascule dans les pratiques d&rsquo;interrogatoire &#8211; Expert en Interviews d&rsquo;investigation, <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-primary-color\">Emily Alison<\/mark><\/strong><\/h1>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/spotifyanchor-web.app.link\/e\/bcrzySG5PLb\">\u00c9couter<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n\n\n\n<section class=\"wp-block-group has-global-padding is-layout-constrained wp-container-core-group-is-layout-884087f6 wp-block-group-is-layout-constrained\" style=\"margin-top:var(--wp--preset--spacing--80);margin-bottom:var(--wp--preset--spacing--80)\">\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-cbe57604 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:300px\">\n<p class=\"is-style-lead\"><strong><a href=\"https:\/\/www.orbitinterviewing.com\/experts\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-primary-color\">Emily Alison<\/mark><\/a>Emily Alison, chercheur associ\u00e9, auteur et psychologue \u00e0 l&rsquo;Universit\u00e9 de Liverpool. <a href=\"https:\/\/www.liverpool.ac.uk\/\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-primary-color\">Universit\u00e9 de Liverpool<\/mark><\/a>Emily Alison, associ\u00e9e, auteur et psychologue \u00e0 l&rsquo;universit\u00e9 de Liverpool, parle de la m\u00e9thode Orbit (Observing Rapport-Based Interpersonal Techniques) d&rsquo;entretien d&rsquo;investigation et de l&rsquo;importance de l&rsquo;\u00e9tablissement de rapports.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><a href=\"https:\/\/www.orbitinterviewing.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-primary-color\">La m\u00e9thode Orbit<\/mark><\/a> est une approche structur\u00e9e de la communication qui se concentre sur l&rsquo;\u00e9tablissement d&rsquo;une relation de confiance et de compr\u00e9hension avec la personne interrog\u00e9e, ce qui permet en fin de compte de recueillir des informations plus pr\u00e9cises et plus fiables. Alison souligne la n\u00e9cessit\u00e9 pour les enqu\u00eateurs de g\u00e9rer leur propre comportement et de s&rsquo;adapter au style de communication de la personne interrog\u00e9e. Elle souligne \u00e9galement l&rsquo;\u00e9volution vers des approches plus scientifiques et \u00e9thiques de l&rsquo;entretien d&rsquo;investigation, comme le montre le <a href=\"https:\/\/davidhorn.com\/resource-hub\/a-new-chapter-in-global-justice-the-manual-on-investigative-interviewing-for-criminal-investigation-has-been-launched\/\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-primary-color\">Manuel de l&rsquo;ONU sur l&rsquo;entretien d&rsquo;investigation<\/mark><\/a> et dans les <a href=\"https:\/\/davidhorn.com\/fr\/resource-hub\/juan-mendez-on-interrogations-and-interviewing\/\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-primary-color\">principes de M\u00e9ndez<\/mark><\/a>.    <\/p>\n\n\n\n<p>Alison encourage les individus \u00e0 adopter l&rsquo;approche scientifique d&rsquo;Orbit et \u00e0 donner la priorit\u00e9 \u00e0 l&rsquo;\u00e9tablissement d&rsquo;une relation \u00e0 tous les stades du processus d&rsquo;entretien.  <\/p>\n<\/div>\n<\/div>\n<\/section>\n\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\" id=\"h-principaux-enseignements-de-la-conversation-sur-les-interviews-d-investigation\">Principaux enseignements de la conversation sur les Interviews d&rsquo;investigation<\/h2>\n\n\n\n<ol start=\"1\" class=\"wp-block-list\">\n<li>La m\u00e9thode Orbit est une approche structur\u00e9e de l&rsquo;entretien d&rsquo;investigation qui se concentre sur l&rsquo;\u00e9tablissement d&rsquo;une relation et d&rsquo;une compr\u00e9hension avec la personne interrog\u00e9e.  <\/li>\n\n\n\n<li>Les enqu\u00eateurs doivent g\u00e9rer leur propre comportement et s&rsquo;adapter au style de communication de la personne interrog\u00e9e afin d&rsquo;obtenir le plus d&rsquo;informations possible.  <\/li>\n\n\n\n<li>On assiste \u00e0 une \u00e9volution vers des approches plus scientifiques et \u00e9thiques de l&rsquo;entretien d&rsquo;investigation, comme en t\u00e9moigne la publication par les Nations unies des <a href=\"https:\/\/www.apt.ch\/our-prioritiesfair-criminal-justice-systems\/principles-effective-interviewing-investigations-and\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-primary-color\">principes M\u00e9ndez<\/mark><\/a>.  <\/li>\n\n\n\n<li>Le mod\u00e8le Orbit est une approche pratique et scientifique visant \u00e0 remplacer les m\u00e9thodes d&rsquo;interrogatoire accusatoires et \u00e0 cr\u00e9er des preuves solides tout en respectant les principes des droits de l&rsquo;homme.  <\/li>\n<\/ol>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-6c531013 wp-block-group-is-layout-flex\"><\/div>\n\n\n\n<div class=\"wp-block-group has-primary-25-background-color has-background has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--50);padding-bottom:var(--wp--preset--spacing--50)\">\n<h2 class=\"wp-block-heading\" id=\"h-a-propos-des-invites\">A propos des invit\u00e9s<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading is-style-lead\" id=\"h-emily-alison\"><strong>Emily Alison<\/strong> <\/h2>\n\n\n\n<p class=\"is-style-lead\">Cr\u00e9ateur et formateur principal d&rsquo;ORBIT  <\/p>\n\n\n\n<p><\/p>\n<\/div>\n\n\n\n<p>Emily Alison travaille comme psychologue consultante en comportement depuis 20 ans, fournissant des traitements \u00e0 la fois dans le secteur de la justice p\u00e9nale et dans la communaut\u00e9.  <\/p>\n\n\n\n<p>Sp\u00e9cialis\u00e9e dans l&rsquo;\u00e9valuation et le traitement de la violence, elle a travaill\u00e9 avec plus de 850 auteurs de violence domestique et a con\u00e7u des interventions th\u00e9rapeutiques pour la violence domestique, la violence entre enfants et parents, les relations saines pour les enfants et les jeunes, les comportements sexuels nuisibles et la prise de risques sexuels chez les adolescents, ainsi que la d\u00e9linquance li\u00e9e aux gangs et aux armes.  <\/p>\n\n\n\n<p>Au cours des dix derni\u00e8res ann\u00e9es, elle a particip\u00e9 \u00e0 l&rsquo;\u00e9laboration de l&rsquo;outil Preventing Violent Extremism pour le profilage de l&rsquo;extr\u00e9misme potentiel et du cadre ORBIT pour les entretiens avanc\u00e9s avec les d\u00e9tenus de grande valeur. Elle a observ\u00e9 plus de 500 heures d&rsquo;entretiens de la police britannique avec des terroristes, couvrant un \u00e9ventail d&rsquo;id\u00e9ologies, notamment paramilitaire, Al-Qa\u00efda, de droite et ISIS. <\/p>\n\n\n\n<p>Emily a form\u00e9 un large \u00e9ventail d&rsquo;organisations, dont le FBI\/CIA\/DoD, le cadre national britannique d&rsquo;entretien contre le terrorisme et l&rsquo;arm\u00e9e britannique au cadre ORBIT pour les m\u00e9thodes d&rsquo;interrogatoire bas\u00e9es sur le rapport.<\/p>\n<\/div>\n<\/div>\n\n\n\n<p><\/p>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-6c531013 wp-block-group-is-layout-flex\"><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-6c531013 wp-block-group-is-layout-flex\"><\/div>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-6c531013 wp-block-group-is-layout-flex\"><\/div>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-6c531013 wp-block-group-is-layout-flex\"><\/div>\n\n\n\n<section class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"margin-top:var(--wp--preset--spacing--80);margin-bottom:var(--wp--preset--spacing--80)\">\n<div class=\"wp-block-group alignwide is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\" id=\"h-produits-apparentes\">Produits apparent\u00e9s<\/h2>\n\n\n\n<div class=\"align wp-block-site-carousel\" id=\"block-b3ef64b9c885c7a81182a722a3090049\">\n\n<div class=\"swiper\">\n\t<div class=\"swiper-button-prev\"><\/div>\n\t<div class=\"swiper-button-next\"><\/div>\n\t<ul class=\"carousel carousel__container swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t<li class=\"carousel__item swiper-slide\">\n\t\t\t\t\t<a href=\"https:\/\/davidhorn.com\/fr\/product\/enregistreur-fixe\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"carousel__figure\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/d3pwq9e4hibwhv.cloudfront.net\/wp-content\/uploads\/2024\/06\/18110937\/DSCF0669-1-1024x683.jpg\">\n\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel__item-content\">\n\t\t\t\t\t\t\t<h2 class=\"carousel__item-title\">Enregistreur fixe d&rsquo;entretiens policiers HD<\/h2>\n\t\t\t\t\t\t\t<p class=\"carousel__item-excerpt\"><p>Enregistreur HD fixe pour les salles d&rsquo;interrogatoire de haute s\u00e9curit\u00e9.<\/p>\n<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li class=\"carousel__item swiper-slide\">\n\t\t\t\t\t<a href=\"https:\/\/davidhorn.com\/fr\/product\/enregistreur-portable\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"carousel__figure\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/d3pwq9e4hibwhv.cloudfront.net\/wp-content\/uploads\/2024\/05\/18111442\/DSCF0515-683x1024.jpg\">\n\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel__item-content\">\n\t\t\t\t\t\t\t<h2 class=\"carousel__item-title\">Enregistreur portable d&rsquo;entretiens policiers<\/h2>\n\t\t\t\t\t\t\t<p class=\"carousel__item-excerpt\"><p>Enregistreur d&rsquo;entretien l\u00e9ger, conforme \u00e0 la norme PACE, pour tout type d&rsquo;environnement.<\/p>\n<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li class=\"carousel__item swiper-slide\">\n\t\t\t\t\t<a href=\"https:\/\/davidhorn.com\/fr\/product\/capture\/\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"carousel__figure\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/d3pwq9e4hibwhv.cloudfront.net\/wp-content\/uploads\/2024\/06\/22070457\/Mobile_product-1024x1007.jpg\">\n\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel__item-content\">\n\t\t\t\t\t\t\t<h2 class=\"carousel__item-title\">Capture &#8211; Enregistrement d&rsquo;entretiens mobiles<\/h2>\n\t\t\t\t\t\t\t<p class=\"carousel__item-excerpt\"><p>Enregistreur d&rsquo;application mobile pour capturer des preuves en d\u00e9placement.<\/p>\n<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n<\/div>\n<div class=\"swiper-pagination\"><\/div>\n\n<\/div>\n<\/div>\n<\/section>\n\n\n\n<section class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"margin-top:var(--wp--preset--spacing--80);margin-bottom:var(--wp--preset--spacing--80)\"><\/section>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-group summary has-primary-25-background-color has-background has-global-padding is-layout-constrained wp-container-core-group-is-layout-1c074333 wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--50);padding-right:var(--wp--preset--spacing--30);padding-bottom:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--30)\">\n<div class=\"wp-block-group summary-wrapper has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\" id=\"h-transcription\">Transcription<\/h2>\n\n\n\n<p><strong>B\u00f8rge Hansen<\/strong> <\/p>\n\n\n\n<p>Bonjour, Emily. Comment allez-vous aujourd&rsquo;hui ?   <\/p>\n\n\n\n<p><strong>Emily Alison<\/strong> <\/p>\n\n\n\n<p>Bonjour. Je vais bien. Comment allez-vous, B\u00f8rge ?    <\/p>\n\n\n\n<p><strong>B\u00f8rge Hansen<\/strong> <\/p>\n\n\n\n<p>Je vais bien. En dehors du temps qu&rsquo;il fait en Norv\u00e8ge, o\u00f9 je me trouve en ce moment, c&rsquo;est tr\u00e8s similaire \u00e0 la premi\u00e8re fois que nous nous sommes rencontr\u00e9s. Nous nous sommes en effet rencontr\u00e9s dans une petite ville tr\u00e8s pittoresque du sud de la Norv\u00e8ge o\u00f9 le temps \u00e9tait magnifique et o\u00f9 nous nous sommes rencontr\u00e9s pour la premi\u00e8re fois, vous, moi, Lawrence et l&rsquo;inspecteur de police norv\u00e9gien Ivar Fahsing. Nous avons parl\u00e9 pour la premi\u00e8re fois du travail que vous avez accompli, du travail que nous accomplissons avec Davidhorn, et de la mani\u00e8re dont nous pouvons collaborer et travailler \u00e0 l&rsquo;expansion du domaine de l&rsquo;interview d&rsquo;investigation.     <\/p>\n\n\n\n<p><strong>Emily Alison<\/strong> <\/p>\n\n\n\n<p>Oui, absolument. Je suis assez jaloux parce qu&rsquo;ici, au Royaume-Uni, nous avons eu environ 10 mois de pluie et elle persiste. Je viens donc de sortir de la pluie ce matin.    <\/p>\n\n\n\n<p><strong>B\u00f8rge Hansen<\/strong>  <\/p>\n\n\n\n<p>Oui, c&rsquo;est vrai. Pouvez-vous, pour nos auditeurs, nous dire un peu qui est Emily Allison ?   <\/p>\n\n\n\n<p><strong>Emily Alison<\/strong> <\/p>\n\n\n\n<p>C&rsquo;est vrai. Oui. J&rsquo;ai donc une question \u00e0 vous poser. Je suis chercheur associ\u00e9 et psychologue \u00e0 l&rsquo;Universit\u00e9 de Liverpool. Je me suis sp\u00e9cialis\u00e9e dans les pratiques d&rsquo;entretien et d&rsquo;interrogatoire depuis au moins 20 ans, dont 12 ans dans le cadre de la recherche. La raison pour laquelle j&rsquo;ai souvent du mal \u00e0 r\u00e9pondre \u00e0 cette question est que j&rsquo;ai \u00e9galement une longue exp\u00e9rience dans le traitement des abus domestiques, principalement pour les auteurs, mais aussi dans l&rsquo;intervention aupr\u00e8s des jeunes, des enfants et des familles. Je l&rsquo;ai mentionn\u00e9 parce que, m\u00eame s&rsquo;il s&rsquo;agit de domaines distincts, il y a beaucoup de chevauchements entre les diff\u00e9rents domaines dans lesquels j&rsquo;ai travaill\u00e9.        <\/p>\n\n\n\n<p><strong>B\u00f8rge Hansen<\/strong> <\/p>\n\n\n\n<p>Vous et votre mari, Lawrence, pour les personnes travaillant dans ce domaine. Si vous faites une recherche en ligne sur vos noms, vous verrez rapidement appara\u00eetre un autre terme, l&rsquo;orbite. Et pour ceux qui creusent un peu plus loin, comme vous le dites, vous avez beaucoup investi dans ce domaine. Alors pourquoi, dans ce domaine de l&rsquo;interview, de l&rsquo;interrogatoire et de tout ce qui s&rsquo;ensuit, vous \u00eates-vous tant concentr\u00e9 sur l&rsquo;\u00e9tablissement d&rsquo;un rapport ? Et pourquoi la m\u00e9thode de l&rsquo;orbite existe-t-elle ? Comment a-t-elle vu le jour ?       <\/p>\n\n\n\n<p><strong>Emily Alison<\/strong> <\/p>\n\n\n\n<p>C&rsquo;est vrai. En gros, Lawrence et moi fournissions des formations et des contributions \u00e0 diverses forces de police. Et, vous savez, mon exp\u00e9rience, qui \u00e9tait beaucoup plus th\u00e9rapeutique, l&rsquo;exp\u00e9rience de Lawrence, qui est vraiment ax\u00e9e sur la prise de d\u00e9cision en cas d&rsquo;incident critique, mais aussi nous avions tous les deux des \u00e9l\u00e9ments de communication et en 2012, nous avons eu l&rsquo;opportunit\u00e9 gr\u00e2ce \u00e0 un financement de recherche obtenu par le HIG, une organisation aux \u00c9tats-Unis qui signifie High Value Detainee Interrogation Group (Groupe d&rsquo;interrogation des d\u00e9tenus de grande valeur) qui roule sur la langue.    <\/p>\n\n\n\n<p>Fondamentalement, ce groupe a \u00e9t\u00e9 cr\u00e9\u00e9 sous l&rsquo;administration Obama pour d\u00e9terminer si nous n&rsquo;allons pas utiliser des techniques d&rsquo;interrogatoire renforc\u00e9es, \u00e9galement connues sous le nom de torture, pour obtenir des informations de la part des terroristes, alors qu&rsquo;allons-nous utiliser et quelle science est disponible pour nous aider \u00e0 r\u00e9soudre ce probl\u00e8me ?  <\/p>\n\n\n\n<p>Le HIG est donc une organisation unique en son genre car, pour de nombreuses raisons, il se concentre sur l&rsquo;utilisation de la recherche scientifique et sa mise en \u0153uvre pour les praticiens de premi\u00e8re ligne. Mais il s&rsquo;agit \u00e9galement d&rsquo;une coop\u00e9ration entre des agences qui ne travaillent normalement pas ensemble de cette mani\u00e8re. La CIA, le FBI et le minist\u00e8re de la d\u00e9fense.    <\/p>\n\n\n\n<p>Et il est int\u00e9ressant de noter que, comme il s&rsquo;agit d&rsquo;une initiative mondiale, nous avons pu obtenir des fonds pour \u00e9tudier ce qui est r\u00e9ellement efficace dans ce contexte. C&rsquo;est ainsi qu&rsquo;est n\u00e9 Orbit.   <\/p>\n\n\n\n<p><strong>B\u00f8rge Hansen<\/strong> <\/p>\n\n\n\n<p>Vous avez donc examin\u00e9 les interrogatoires et les entretiens pass\u00e9s et vous avez d\u00e9chiffr\u00e9 ce qui a fonctionn\u00e9 et ce qui n&rsquo;a pas fonctionn\u00e9. Est-ce le cas ?   <\/p>\n\n\n\n<p><strong>Emily Alison<\/strong> <\/p>\n\n\n\n<p>Tout \u00e0 fait. Dans ce domaine, je veux dire que cela semble tr\u00e8s simple de la fa\u00e7on dont vous le dites. Car l&rsquo;un des probl\u00e8mes dans ce domaine est qu&rsquo;une grande partie de la recherche est difficile d&rsquo;acc\u00e9der \u00e0 ces donn\u00e9es. Il s&rsquo;agit de donn\u00e9es tr\u00e8s sensibles. Les agences se sentent souvent tr\u00e8s mal \u00e0 l&rsquo;aise \u00e0 l&rsquo;id\u00e9e d&rsquo;autoriser un examen acad\u00e9mique de ces donn\u00e9es. Il s&rsquo;agissait donc d&rsquo;une v\u00e9ritable mesure de la confiance que Lawrence et moi-m\u00eame avions acquise au cours de nos pr\u00e9c\u00e9dentes ann\u00e9es de travail avec la police britannique et de la confiance qu&rsquo;ils nous accordaient pour nous permettre d&rsquo;examiner des entretiens r\u00e9els avec des personnes soup\u00e7onn\u00e9es de terrorisme. Toutes les donn\u00e9es sur lesquelles repose Orbit ont donc \u00e9t\u00e9 reproduites sur des suspects d&rsquo;abus sexuels sur enfants et d&rsquo;images ind\u00e9centes.        <\/p>\n\n\n\n<p>Sungwon Kim, ancien officier de police et chercheur sud-cor\u00e9en, a \u00e9galement reproduit l&rsquo;exp\u00e9rience avec des victimes d&rsquo;agressions sexuelles. Il s&rsquo;agit donc de donn\u00e9es r\u00e9elles. Et c&rsquo;est en fait assez unique dans ce genre d&rsquo;espace o\u00f9 l&rsquo;on ne demande pas aux \u00e9tudiants de faire semblant d&rsquo;\u00eatre des terroristes pour obtenir un bon pour une pizza \u00e0 la fin.    <\/p>\n\n\n\n<p><strong>B\u00f8rge Hansen<\/strong> <\/p>\n\n\n\n<p>C&rsquo;est parce que, d&rsquo;apr\u00e8s mon exp\u00e9rience, nous constatons que les enqu\u00eateurs ou les officiers de police sont g\u00e9n\u00e9ralement form\u00e9s par d&rsquo;autres \u00e9tudiants sur la base de simulations plut\u00f4t que sur la base de cas r\u00e9els. Et leur formation est bas\u00e9e non pas sur des enqu\u00eates ou des cas r\u00e9els, mais plut\u00f4t sur des simulations. Quelle est la diff\u00e9rence, selon vous ? Parce que vous dites que vous vous basez sur vos m\u00e9thodes et que vous devez ensuite vous former sur celles-ci, mais sur des cas r\u00e9els.     <\/p>\n\n\n\n<p><strong>Emily Alison<\/strong> <\/p>\n\n\n\n<p>Oui, je pense que pour moi, il ne s&rsquo;agit pas de dire qu&rsquo;il n&rsquo;y a pas de valeur \u00e0 tirer d&rsquo;une recherche plus exp\u00e9rimentale avec des \u00e9tudiants, parce que l&rsquo;avantage de cela est que vous pouvez contr\u00f4ler fortement les variables que vous examinez. Mais le probl\u00e8me, c&rsquo;est qu&rsquo;elles ne se traduisent pas directement par l&rsquo;obscurit\u00e9, la grisaille et la complexit\u00e9 de l&rsquo;environnement r\u00e9el. Par exemple, dans le cadre d&rsquo;un entretien, il existe une technique courante appel\u00e9e \u00ab\u00a0entonnoir\u00a0\u00bb, qui consiste \u00e0 commencer par une s\u00e9rie de questions tr\u00e8s g\u00e9n\u00e9rales qui ouvrent le compte-rendu de la personne. Vous commencez par une s\u00e9rie de questions tr\u00e8s g\u00e9n\u00e9rales qui ouvrent le r\u00e9cit de la personne. Vous dites : \u00ab\u00a0Dites-moi tout ce dont vous vous souvenez sur les \u00e9v\u00e9nements du week-end\u00a0\u00bb. Ensuite, vous passez \u00e0 des questions plus sp\u00e9cifiques.      <\/p>\n\n\n\n<p>Le probl\u00e8me, c&rsquo;est que si vous avez quelqu&rsquo;un qui n&rsquo;est pas tr\u00e8s motiv\u00e9 pour vous r\u00e9sister, et par l\u00e0 je veux dire form\u00e9 au contre-interrogatoire, potentiellement, vous savez, il va en fait vous barrer la route et vous donner un silence total. Comment allez-vous demander \u00e0 quelqu&rsquo;un un compte rendu g\u00e9n\u00e9ral et plus pr\u00e9cis si c&rsquo;est ce que vous avez en face de vous ? Cela vous renseigne donc sur la mani\u00e8re dont les gens communiquent et vous donne des principes pour effectuer ce type de recherche transf\u00e9rable. Mais pour nous, il s&rsquo;agissait d&rsquo;entrer directement dans la boue et la complexit\u00e9 de ce \u00e0 quoi cela ressemble vraiment. Regardez ce que font les enqu\u00eateurs pour s\u00e9curiser les informations. Et nous ne parlons pas de n&rsquo;importe quelle information. Il s&rsquo;agit d&rsquo;informations qui ont une valeur de renseignement ou de preuve. Mais regardons aussi ce qu&rsquo;ils font pour se mettre en travers de leur propre chemin. Qu&rsquo;est-ce qui emp\u00eache la circulation de l&rsquo;information ?          <\/p>\n\n\n\n<p>Dans un contexte tr\u00e8s difficile, avec des personnes tr\u00e8s r\u00e9sistantes, vous savez, des personnes qui peuvent \u00eatre trompeuses, qui peuvent, comme je l&rsquo;ai dit, utiliser l&rsquo;\u00e9vitement total, vous savez, se retourner et faire face au mur \u00e0 des personnes qui vont en fait, vous savez, vouloir faire ce que nous appelons du backfooting. Il s&rsquo;agit d&rsquo;attaquer verbalement l&rsquo;Interviews et ce qu&rsquo;il repr\u00e9sente afin de d\u00e9tourner l&rsquo;attention et de se soustraire aux questions. Les \u00e9tudes r\u00e9alis\u00e9es par les \u00e9tudiants peinent \u00e0 reproduire l&rsquo;intensit\u00e9 et la complexit\u00e9 de l&rsquo;environnement dans lequel les agents travaillent r\u00e9ellement.    <\/p>\n\n\n\n<p><strong>B\u00f8rge Hansen<\/strong> <\/p>\n\n\n\n<p>Selon vous, quel est le facteur le plus d\u00e9terminant ? Est-ce l&rsquo;intervieweur ou l&rsquo;interview\u00e9, parce que, vous savez, vous d\u00e9crivez des situations o\u00f9 peut-\u00eatre, vous savez, les gens, comme vous le dites, vous font obstruction ou vous distraient de toutes les fa\u00e7ons possibles, volontairement ou involontairement, pour que vous puissiez progresser dans votre entretien. Est-ce que c&rsquo;est l&rsquo;interview\u00e9 qui pose probl\u00e8me ou est-ce que ce sont les intervieweurs ?    <\/p>\n\n\n\n<p><strong>Emily Alison<\/strong> <\/p>\n\n\n\n<p>Je pense que j&rsquo;aimerais pouvoir donner une r\u00e9ponse d\u00e9finitive. Je pense qu&rsquo;il peut y avoir les deux. Mais pour moi, quel est le seul facteur que vous pouvez contr\u00f4ler ? C&rsquo;est l&rsquo;intervieweur. C&rsquo;est donc \u00e0 lui de g\u00e9rer son propre comportement et de g\u00e9rer le comportement du suspect, le comportement du d\u00e9tenu. En d&rsquo;autres termes, nous savons, d&rsquo;apr\u00e8s le mod\u00e8le orbital, qu&rsquo;il s&rsquo;agit de mod\u00e8les de communication instinctifs. C&rsquo;est-\u00e0-dire les fa\u00e7ons dont les gens r\u00e9agissent les uns aux autres. C&rsquo;est pourquoi vous obtenez ce transfert vers, vous savez, toutes sortes de relations, comment les gens s&rsquo;entendent ou non.         <\/p>\n\n\n\n<p>C&rsquo;est pourquoi nous pouvons aider l&rsquo;intervieweur \u00e0 g\u00e9rer \u00e0 peu pr\u00e8s n&rsquo;importe quelle forme de comportement de l&rsquo;interview\u00e9. La responsabilit\u00e9 lui incombe donc, comme il se doit. C&rsquo;est lui qui est le professionnel dans la pi\u00e8ce. C&rsquo;est une obligation qui lui incombe. Si l&rsquo;autre personne veut r\u00e9sister et tenter de dissimuler ou de tromper, c&rsquo;est son choix. L&rsquo;intervieweur doit se g\u00e9rer lui-m\u00eame.       <\/p>\n\n\n\n<p><strong>B\u00f8rge Hansen<\/strong>  <\/p>\n\n\n\n<p>Dans le mat\u00e9riel sur lequel vous avez fait des recherches, il y a toutes sortes de situations, n&rsquo;est-ce pas ? Des gens qui collaborent et d&rsquo;autres qui ne collaborent pas.   <\/p>\n\n\n\n<p><strong>Emily Alison<\/strong> <\/p>\n\n\n\n<p>Oui, absolument. Vous pouvez donc avoir quelqu&rsquo;un qui parle beaucoup et qui est vraiment coop\u00e9ratif lors de l&rsquo;entretien avec la police ou qui en a l&rsquo;air, mais qui ne r\u00e9pond en fait \u00e0 aucune question. Toutes ses r\u00e9ponses sont donc relativement vagues. Elle essaie de d\u00e9tourner l&rsquo;attention en abordant d&rsquo;autres sujets.     <\/p>\n\n\n\n<p>Et c&rsquo;est tr\u00e8s diff\u00e9rent des autres situations que j&rsquo;ai d\u00e9crites, o\u00f9 ils peuvent \u00eatre verbalement agressifs ou totalement silencieux. Vous savez, ce sont des d\u00e9fis interpersonnels intenses qui, vous le savez, sont assez uniques \u00e0 ce type d&rsquo;environnement. Mais les gens peuvent penser que, si vous avez affaire \u00e0 votre adolescent et qu&rsquo;il vous oppose un silence total ou qu&rsquo;il vous agresse verbalement parce qu&rsquo;il ne veut pas parler de ce que vous essayez de lui dire, vous pouvez vous demander ce qui se passe.    <\/p>\n\n\n\n<p><strong>B\u00f8rge Hansen<\/strong> <\/p>\n\n\n\n<p>Il y a donc des parall\u00e8les. J&rsquo;ai une fille adolescente, alors j&rsquo;ai h\u00e2te d&rsquo;apprendre comment g\u00e9rer le roulement des yeux. mon Dieu, comme elle dit. Dites-moi, lorsque vous avez commenc\u00e9 \u00e0 travailler sur ce sujet, quel \u00e9tait le premier type de science sur lequel vous vous \u00eates pench\u00e9s ? Structur\u00e9e, parce que l&rsquo;orbite est une m\u00e9thode tr\u00e8s structur\u00e9e pour faire face \u00e0 diff\u00e9rentes situations. Et puis, vous savez, lorsque vous faites des recherches et que vous voyez ce qui fonctionne, cela n&rsquo;a pas fonctionn\u00e9. Comment cela s&rsquo;est-il produit ? Parce que, vous savez, en d\u00e9chiffrant tout cela, je me souviens que vous avez dit tout \u00e0 l&rsquo;heure qu&rsquo;il s&rsquo;agissait de plusieurs milliers d&rsquo;Interviews, n&rsquo;est-ce pas ? Il s&rsquo;agit donc de d\u00e9chiffrer et de comprendre ce qui se passe, car toutes les personnes sont diff\u00e9rentes et les situations sont diff\u00e9rentes. Comment cat\u00e9gorisez-vous et construisez-vous une structure \u00e0 partir de cela ?           <\/p>\n\n\n\n<p><strong>Emily Alison<\/strong> <\/p>\n\n\n\n<p>Oui, absolument. Nous avons cod\u00e9 plus de 2000 heures d&rsquo;entretiens, d&rsquo;entretiens suspects. Et quand je dis cod\u00e9, c&rsquo;est exactement ce que nous faisons, comme vous l&rsquo;avez d\u00e9crit, nous cherchons \u00e0 savoir quel est le syst\u00e8me sous-jacent qui sous-tend les styles de communication. \u00c0 mon avis, il s&rsquo;agit simplement de mettre en place une sorte de structure autour de nos modes de communication et des \u00e9l\u00e9ments qui facilitent la communication ou \u00e9tablissent un rapport, et des \u00e9l\u00e9ments qui l&rsquo;entravent ou y font obstacle. C&rsquo;est pourquoi Orbit vous apporte deux choses. Il vous offre un outil de diagnostic qui vous permet de regarder la personne en face de vous et de vous demander comment elle aime communiquer. Aime-t-elle les choses totalement directes ? Aime-t-elle un bavardage social plus chaleureux ? Veut-elle que l&rsquo;autre personne prenne en charge la situation ?          <\/p>\n\n\n\n<p>Orbit vous donne ce type de carte interpersonnelle et vous indique \u00e9galement comment ils vont r\u00e9agir \u00e0 votre r\u00e9ponse. De cette mani\u00e8re, il peut vous donner une strat\u00e9gie pour aller de l&rsquo;avant. Si vous rencontrez une question ou un probl\u00e8me avec un interlocuteur particulier, Orbit vous donne une recommandation sur la mani\u00e8re de l&rsquo;aborder, qui sera adapt\u00e9e \u00e0 cette personne et \u00e0 son style individuel.    <\/p>\n\n\n\n<p>Et cela provient de notre exp\u00e9rience, comme je l&rsquo;ai dit, en tant que psychologues, des principes de base de la communication sociale et de la th\u00e9orie de la personnalit\u00e9. Nous nous sommes donc appuy\u00e9s sur un grand nombre de principes fondamentaux tir\u00e9s de la litt\u00e9rature. Ainsi, des choses comme le circumplex interpersonnel de Timothy Leary, qui \u00e9tudie la fa\u00e7on dont les gens r\u00e9agissent les uns aux autres dans la communication et comment cela est influenc\u00e9 par leur personnalit\u00e9, s&rsquo;int\u00e8grent dans le mod\u00e8le. Nous nous sommes inspir\u00e9s de l&rsquo;entretien motivationnel, de Rolnick et Miller, et des th\u00e9ories humanistes de la communication. Il s&rsquo;agit donc d&rsquo;une approche plus rogerienne, ce qui est tr\u00e8s int\u00e9ressant, car la th\u00e9orie de Carl Rogers, que j&rsquo;appelle l&rsquo;anti Freud, repose sur l&rsquo;id\u00e9e que le th\u00e9rapeute ou la personne qui m\u00e8ne l&rsquo;entretien n&rsquo;est pas l&rsquo;expert de la personne interrog\u00e9e. C&rsquo;est lui qui l&rsquo;est. C&rsquo;est lui qui d\u00e9tient l&rsquo;information. Donc, si vous voulez d\u00e9bloquer cette information et la faire parler, vous devez la comprendre. Il ne s&rsquo;agit pas d&rsquo;apprendre une astuce, une tactique ou une tromperie particuli\u00e8re que vous pouvez utiliser pour le faire parler. Il s&rsquo;agit de les comprendre de mani\u00e8re \u00e0 ce qu&rsquo;ils se sentent capables de communiquer. Je sais que cela semble un peu, je veux dire, c&rsquo;est tr\u00e8s bien pour l&rsquo;\u00e9ducation des enfants dans un espace plus conflictuel qui peut sembler un peu \u00e9tranger, je pense, aux agents. Mais ce que nous avons dit, c&rsquo;est quel est le but de ce que vous faites ? C&rsquo;est d&rsquo;obtenir ces informations.              <\/p>\n\n\n\n<p><strong>B\u00f8rge Hansen<\/strong> <\/p>\n\n\n\n<p>Vous appliquez donc l&#8217;empathie \u00e0 la situation, vous n&rsquo;\u00eates pas sympathique et vous n&rsquo;\u00eates pas d&rsquo;accord avec l&rsquo;enqu\u00eateur s&rsquo;il est suspect. Mais est-ce que le fait d&rsquo;appliquer l&#8217;empathie \u00e0 la situation dans laquelle vous vous trouvez vous permet d&rsquo;\u00e9tablir une relation bas\u00e9e sur cette empathie ?   <\/p>\n\n\n\n<p>Absolument. C&rsquo;est l&rsquo;un des principes fondamentaux. Nous les appelons les \u00ab\u00a0principes ici\u00a0\u00bb dans le mod\u00e8le orbital. Le premier est l&rsquo;honn\u00eatet\u00e9. Le second est l&#8217;empathie. Ces deux principes sont probablement les plus fondamentaux pour \u00e9tablir une relation de confiance avec quelqu&rsquo;un.       <\/p>\n\n\n\n<p><strong>Emily Alison<\/strong> <\/p>\n\n\n\n<p>et la compr\u00e9hension. Et c&rsquo;est ce que vous visez. Ce n&rsquo;est pas un accord. Et comme vous le dites, Berger, ce n&rsquo;est pas de la sympathie. Il ne s&rsquo;agit en aucun cas d&rsquo;excuser, d&rsquo;approuver ou d&rsquo;excuser le comportement de l&rsquo;autre personne ou ce qu&rsquo;elle dit. Vous essayez de comprendre son \u00e9tat d&rsquo;esprit, pourquoi il a choisi d&rsquo;agir comme il l&rsquo;a fait, quelles sont ses valeurs fondamentales, ce qui lui tient \u00e0 c\u0153ur. C&rsquo;est cette curiosit\u00e9 qui compte. Notre slogan est donc de dire que vous devez mener votre communication \u00e0 partir d&rsquo;une position de curiosit\u00e9 et non de suspicion.         <\/p>\n\n\n\n<p><strong>B\u00f8rge Hansen<\/strong> <\/p>\n\n\n\n<p>Autrefois, les enqu\u00eateurs \u00e9taient form\u00e9s par d&rsquo;autres enqu\u00eateurs et si vous \u00e9chouiez ou n&rsquo;excelliez pas, eh bien, vous n&rsquo;\u00e9tiez pas une personne \u00e0 part enti\u00e8re. C&rsquo;est ce qu&rsquo;ils disaient. Mais vous adoptez ici une approche tr\u00e8s diff\u00e9rente. Il s&rsquo;agit d&rsquo;une d\u00e9marche beaucoup plus structur\u00e9e que le simple fait d&rsquo;avoir des astuces ou d&rsquo;\u00eatre coach\u00e9 par d&rsquo;autres. Il s&rsquo;agit d&rsquo;une m\u00e9thode scientifique qui permet de savoir si tout le monde peut apprendre.      <\/p>\n\n\n\n<p><strong>Emily Alison<\/strong> <\/p>\n\n\n\n<p>Oui, les gens disent souvent que l&rsquo;\u00e9tablissement de rapports est une comp\u00e9tence interpersonnelle que l&rsquo;on a ou que l&rsquo;on n&rsquo;a pas. Et il y a certainement une sorte de mesure de base pour savoir si vous avez ces comp\u00e9tences naturellement ou non. Mais avec Orbit, comme je l&rsquo;ai dit, vous disposez d&rsquo;une feuille de route sur la mani\u00e8re d&rsquo;\u00e9tablir un rapport, sur les styles de communication qui seront efficaces, et que tout le monde peut apprendre. C&rsquo;est un effort et cela demande de la pratique parce que parfois vous devez le faire. En ce qui me concerne, par exemple, je suis s\u00fbr que je d\u00e9voile ici mes racines du Midwest, mais je peux \u00eatre un peu autoritaire et j&rsquo;aime \u00eatre bavard. C&rsquo;est donc ma zone de confort. Et je sais ceci \u00e0 propos de ma personnalit\u00e9. Je d\u00e9teste les conflits. Je le d\u00e9teste absolument, mais je peux le faire maintenant. Apr\u00e8s 20 ans d&rsquo;enseignement, de formation et de recherche sur l&rsquo;orbite, si vous me mettez dans une situation de conflit, je sais ce que je suis cens\u00e9 faire pour \u00eatre efficace dans ce genre de zone. Pour moi, c&rsquo;est de la poudre d&rsquo;or, car il n&rsquo;est pas naturel pour tout le monde d&rsquo;\u00eatre bon dans tous ces diff\u00e9rents styles, mais vous pouvez l&rsquo;apprendre. Pour moi, c&rsquo;est une r\u00e9v\u00e9lation de penser que je n&rsquo;ai pas besoin d&rsquo;\u00eatre mal \u00e0 l&rsquo;aise dans ces situations parce que cela m&rsquo;aide \u00e0 comprendre ce qu&rsquo;il faut faire.              <\/p>\n\n\n\n<p><strong>B\u00f8rge Hansen<\/strong> <\/p>\n\n\n\n<p>Ce qui s\u00e9pare_ Donc, comme vous l&rsquo;avez dit, il s&rsquo;agit de comp\u00e9tences interpersonnelles. Qui a g\u00e9n\u00e9ralement du mal \u00e0 apprendre et qui excelle dans cet apprentissage ? Vous avez form\u00e9 un grand nombre de personnes au fil des ans. Quelle est la tendance ? Qui excelle et comment les gens se d\u00e9battent-ils dans ce domaine ?      <\/p>\n\n\n\n<p><strong>Emily Alison<\/strong> <\/p>\n\n\n\n<p>C&rsquo;est une question tr\u00e8s personnelle. L&rsquo;une des premi\u00e8res choses que nous faisons avec les gens, c&rsquo;est de leur demander, et vous pouvez en fait, nous avons un lien que nous venons de mettre sur notre site web, www.orbinterviewing.com. C&rsquo;est un lien vers un questionnaire sur la communication qui vous dit en quelque sorte ce qu&rsquo;il en est. Il s&rsquo;agit d&rsquo;un lien vers un questionnaire sur la communication qui vous informe. La premi\u00e8re chose \u00e0 faire est donc de prendre conscience de soi, et ce questionnaire vous indique les choses pour lesquelles vous \u00eates tr\u00e8s dou\u00e9, celles pour lesquelles vous \u00eates naturellement \u00e0 l&rsquo;aise, et celles pour lesquelles vous aurez des difficult\u00e9s, ou pour lesquelles vous nuirez \u00e0 la communication. Alors, si vous allez mal tourner, \u00e0 quoi cela ressemble-t-il pour vous ? C&rsquo;est en quelque sorte par l\u00e0 que nous commen\u00e7ons, et c&rsquo;est tellement diff\u00e9rent pour chacun. Je dirais que lorsque les gens ont \u00e9t\u00e9 endoctrin\u00e9s dans un syst\u00e8me qui est tr\u00e8s formel et qui retire presque l&rsquo;humanit\u00e9 de la communication, c&rsquo;est souvent un probl\u00e8me.        <\/p>\n\n\n\n<p>Ils sont tellement enferm\u00e9s dans la proc\u00e9dure et la structure, ce qui est important. Dans ces espaces professionnels, il est important d&rsquo;avoir une structure. Cependant, si cela se fait au d\u00e9triment de la communication et de la connexion, alors vous allez limiter massivement la quantit\u00e9 d&rsquo;informations. Pensez \u00e0 ce qui se passe quand les gens, si vous allez au cabinet du m\u00e9decin et qu&rsquo;ils ont un, vous savez, disons qu&rsquo;ils font une \u00e9valuation avec vous sur des probl\u00e8mes potentiels concernant, je ne sais pas, le diab\u00e8te ou, vous savez, n&rsquo;importe quoi. Il pourrait s&rsquo;agir d&rsquo;une \u00e9valuation. S&rsquo;il utilise une liste de contr\u00f4le sous forme de formule, m\u00eame si vous avez quelque chose qui vous pr\u00e9occupe ou que vous pensez \u00eatre vrai, vous pourriez h\u00e9siter ou \u00eatre r\u00e9ticent \u00e0 le dire parce que c&rsquo;est juste rapide, rapide, rapide pour passer \u00e0 la question suivante. Connaissez-vous la r\u00e9ponse \u00e0 cette question ou non ? Et vous n&rsquo;avez pas vraiment le temps de r\u00e9fl\u00e9chir, de penser ou de vous dire : \u00ab\u00a0En fait, je pourrais le r\u00e9v\u00e9ler m\u00eame si c&rsquo;est un peu d\u00e9licat\u00a0\u00bb. Je pense donc que nous essayons souvent de ramener les gens \u00e0 leur humanit\u00e9 dans leur communication.          <\/p>\n\n\n\n<p><strong>B\u00f8rge Hansen<\/strong> <\/p>\n\n\n\n<p>Donc, d&rsquo;une certaine mani\u00e8re, avec le cadre Orbit, pour \u00eatre un bon intervieweur, vous devez commencer par vous-m\u00eame et \u00eatre conscient de qui vous \u00eates et de la fa\u00e7on dont vous \u00eates per\u00e7u par les autres. Est-ce la voie \u00e0 suivre ?   <\/p>\n\n\n\n<p><strong>Emily Alison<\/strong>  <\/p>\n\n\n\n<p>Oui, absolument. Oui, c&rsquo;est certain. Et je pense, je veux dire, que nous pourrions lier cela \u00e0 ce qui vous rend bon en mati\u00e8re d&#8217;empathie. L&#8217;empathie se construit en trois \u00e9tapes. La premi\u00e8re consiste \u00e0 comprendre ses propres pens\u00e9es et sentiments \u00e0 propos des choses. Si vous ne pouvez pas l&rsquo;exprimer, vous \u00eates d\u00e9j\u00e0 limit\u00e9. La deuxi\u00e8me \u00e9tape est la suivante : pouvez-vous voir les choses du point de vue des autres ? Si vous \u00e9tiez dans leur situation ?         <\/p>\n\n\n\n<p>Que ressentiriez-vous ? Que penseriez-vous ? Mais nous parlons ici de la troisi\u00e8me \u00e9tape de l&#8217;empathie, qui est en quelque sorte ce que j&rsquo;appelle l&#8217;empathie cognitive clinique, c&rsquo;est-\u00e0-dire si j&rsquo;\u00e9tais vraiment vous. Pour ce faire, je dois consid\u00e9rer, je veux dire, je connais un peu, vous savez, votre pass\u00e9 et l&rsquo;endroit o\u00f9 vous avez grandi et des choses comme \u00e7a, mais je dois essayer d&rsquo;imaginer, eh bien, si j&rsquo;avais eu ces exp\u00e9riences, est-ce que je le ferais ?     <\/p>\n\n\n\n<p>Est-ce que je prendrais les m\u00eames d\u00e9cisions que vous ? C&rsquo;est pourquoi c&rsquo;est un v\u00e9ritable d\u00e9fi. C&rsquo;est une v\u00e9ritable expertise que d&rsquo;\u00eatre capable de faire cela avec les gens.    <\/p>\n\n\n\n<p><strong>B\u00f8rge Hansen<\/strong> <\/p>\n\n\n\n<p>En appliquant ce niveau avanc\u00e9 d&#8217;empathie, vous \u00eates en mesure de mieux communiquer avec les gens et c&rsquo;est le moyen de parvenir \u00e0 une fin. Il s&rsquo;agit donc d&rsquo;un moyen d&rsquo;obtenir, vous savez, de construire des rapports pour que les gens puissent se connecter \u00e0 vous et que vous puissiez ensuite avoir une conversation. C&rsquo;est tout ?    <\/p>\n\n\n\n<p><strong>Emily Alison<\/strong> <\/p>\n\n\n\n<p>Oui, je veux dire que l&rsquo;une des fa\u00e7ons dont nous parlons souvent de cela est que l&rsquo;autre personne se sent vue par vous. Ce n&rsquo;est donc pas vraiment, parfois il y a ce st\u00e9r\u00e9otype de rapport qui est comme, nous allons trouver, nous allons trouver un lien. Parce que j&rsquo;ai grandi dans un petit endroit isol\u00e9 et enneig\u00e9. Et je sais que vous aussi. Je pourrais essayer de dire, eh bien, cela fait de nous les m\u00eames, vous savez, et n&rsquo;est-ce pas un lien ? Et c&rsquo;est bien. Et c&rsquo;est authentique. Si je mentais, que j&rsquo;avais grandi \u00e0 New York et que j&rsquo;essayais de vous bluffer, cela deviendrait un pi\u00e8ge. En revanche, ce que nous disons \u00e0 propos de l&rsquo;\u00e9tablissement d&rsquo;un rapport, c&rsquo;est qu&rsquo;il importe peu que vous et moi ayons des similitudes ou non. Je dois simplement essayer de comprendre les choses de votre point de vue.            <\/p>\n\n\n\n<p>C&rsquo;est plus facile si nous avons des exp\u00e9riences communes que si nous n&rsquo;en avons pas. Mais si ce n&rsquo;est pas le cas, je peux toujours me mettre dans cet \u00e9tat d&rsquo;esprit et essayer de voir les choses de votre point de vue. Et ce que j&rsquo;allais dire \u00e0 ce sujet, c&rsquo;est que lorsque vous \u00eates capable de le faire et de le faire bien et de voir ce qui int\u00e9resse quelqu&rsquo;un, ses valeurs, ce qu&rsquo;il pense et ressent \u00e0 propos de certaines choses, il se sent vu par vous. C&rsquo;est important.     <\/p>\n\n\n\n<p>Parce qu&rsquo;elle permet de tisser des liens avec des personnes qui nous sont ch\u00e8res. Mais dans le cadre d&rsquo;un entretien avec un suspect, lorsqu&rsquo;une personne se sent vue par vous, il lui est plus difficile de mentir. C&rsquo;est un avantage. Ainsi, une fois qu&rsquo;il se sent v\u00e9ritablement per\u00e7u par vous, il lui est plus difficile d&rsquo;\u00eatre trompeur lorsque vous lui posez des questions directes et franches.     <\/p>\n\n\n\n<p><strong>B\u00f8rge Hansen<\/strong> <\/p>\n\n\n\n<p>En orbite, il y a un quadrant ou un cercle avec quatre quadrants. Vous avez ensuite plac\u00e9 des animaux dans les diff\u00e9rents types de comportement. Pourriez-vous nous en parler un peu ? Il y a de tout, des souris aux dinosaures.     <\/p>\n\n\n\n<p><strong>Emily Alison<\/strong> <\/p>\n\n\n\n<p>Oui. Les animaux, c&rsquo;est un peu, c&rsquo;est venu parce que je faisais ce travail de communication avec les familles apr\u00e8s la violence et que j&rsquo;essayais de r\u00e9tablir la communication entre les parents et les enfants. Il y avait eu beaucoup de traumatismes dans le foyer, mais c&rsquo;\u00e9tait une fa\u00e7on d&rsquo;enseigner m\u00eame \u00e0 un enfant de cinq ou six ans des techniques de communication sophistiqu\u00e9es. Il s&rsquo;agissait donc de savoir quel animal est la maman la plupart du temps. Est-elle un lion autoritaire ? Une souris timide ? Est-ce un singe effront\u00e9 ou un T rex effrayant ? Quel animal est le papa ? Quel animal \u00eates-vous ? J&rsquo;utilise les animaux comme des surnoms, mais nos professionnels s&rsquo;en sont empar\u00e9s et nous ont dit que nous aimions cela. C&rsquo;est facile \u00e0 retenir parce que ce que vous \u00eates en r\u00e9alit\u00e9.            <\/p>\n\n\n\n<p><strong>B\u00f8rge Hansen<\/strong> <\/p>\n\n\n\n<p>Les animaux sont donc rest\u00e9s.  <\/p>\n\n\n\n<p><strong>Emily Alison<\/strong> <\/p>\n\n\n\n<p>Oui, oui, exactement. Les gens aiment \u00e7a. Mais ensuite, nous finissons par dire : \u00ab\u00a0Eh bien, vous savez, qui \u00eates-vous ? Quel est votre domaine de pr\u00e9dilection ? Je me d\u00e9cris comme un singe-lion. J&rsquo;aime que les choses soient chaleureuses et amicales et qu&rsquo;il y ait de la conversation. Et je peux \u00eatre un peu autoritaire et aimer prendre les choses en main. Demandez \u00e0 mon adolescent. Mais d&rsquo;autres personnes aiment recevoir. Elles aiment \u00e9couter. Elles aiment \u00eatre plus en retrait. D&rsquo;autres encore pr\u00e9f\u00e8rent le mode T -Rex, qui est, je veux dire, tout \u00e0 fait Lawrence. Nous rions toujours parce que nous sommes totalement oppos\u00e9s.              <\/p>\n\n\n\n<p>Vous savez, il n&rsquo;a aucun probl\u00e8me avec les conflits et les g\u00e8re tr\u00e8s bien, il est tr\u00e8s assertif, confiant, franc, direct et direct. Il s&rsquo;agit l\u00e0 de comp\u00e9tences interpersonnelles diff\u00e9rentes, dont certaines sont naturelles et d&rsquo;autres doivent \u00eatre travaill\u00e9es. Mais c&rsquo;est le genre de mod\u00e8le avec lequel nous commen\u00e7ons : quel est votre style ? Quel est celui de la personne en face de vous ? Quel est son style et qu&rsquo;est-ce qui lui correspond le mieux ?      <\/p>\n\n\n\n<p><strong>B\u00f8rge Hansen<\/strong> <\/p>\n\n\n\n<p>C&rsquo;est une fa\u00e7on de naviguer ou de cat\u00e9goriser les diff\u00e9rents types de comportements et de savoir comment y r\u00e9pondre.  <\/p>\n\n\n\n<p><strong>Emily Alison<\/strong> <\/p>\n\n\n\n<p>Je dirais certainement naviguer, parce qu&rsquo;il y a un flux. Au cours d&rsquo;une m\u00eame conversation, vous pouvez vous d\u00e9placer dans ce cadre, c&rsquo;est pourquoi nous disons qu&rsquo;il s&rsquo;agit d&rsquo;abord d&rsquo;un diagnostic, puis d&rsquo;une carte. C&rsquo;est une feuille de route pour savoir o\u00f9 je dois mener cette communication. Ainsi, si je dois avoir une conversation difficile sur un sujet, je sais que je vais devoir \u00eatre franc et direct. Quelle r\u00e9action cela va-t-il susciter ? Je peux utiliser la carte pour la pr\u00e9voir et la g\u00e9rer. C&rsquo;est tr\u00e8s stimulant, surtout dans les situations de communication d\u00e9licates, lorsque vous devez demander aux gens de vous rembourser ou que vous devez dire, je crois que nous en avons une dans le livre, que vous devez dire \u00e0 votre p\u00e8re qu&rsquo;il va peut-\u00eatre devoir renoncer \u00e0 son permis de conduire, \u00e0 votre p\u00e8re \u00e2g\u00e9. C&rsquo;est une conversation embarrassante et difficile. C&rsquo;est tr\u00e8s \u00e9mouvant. Comment avoir cette conversation et la mener \u00e0 bien pour qu&rsquo;elle ne nuise pas \u00e0 vos relations mutuelles ?           <\/p>\n\n\n\n<p><strong>B\u00f8rge Hansen<\/strong>  <\/p>\n\n\n\n<p>Si nous changeons un peu de vitesse, l&rsquo;orbite et l&rsquo;\u00e9tablissement de rapports sont cruciaux pour les relations interpersonnelles. R\u00e9cemment, nous avons appris que les Nations Unies ont publi\u00e9 un manuel pour les entretiens d&rsquo;investigation dans le cadre d&rsquo;enqu\u00eates criminelles. Comment voyez-vous Orbit dans le contexte des entretiens d&rsquo;investigation ? Nous constatons qu&rsquo;une grande partie des pratiques en mati\u00e8re d&rsquo;entretiens d&rsquo;investigation ont vu le jour au Royaume-Uni. Des travaux ont \u00e9t\u00e9 men\u00e9s dans les pays nordiques. Elles font maintenant partie des principes de Mendes des Nations Unies. Le manuel est arriv\u00e9. O\u00f9 voyez-vous Orbit ? Et comment voyez-vous l&rsquo;\u00e9volution de ce qui se passe dans le monde, o\u00f9 l&rsquo;on s&rsquo;int\u00e9resse de plus en plus \u00e0 ce type d&rsquo;enqu\u00eates ? Quelles sont vos observations ? Vous travaillez dans ce domaine depuis un certain temps d\u00e9j\u00e0.            <\/p>\n\n\n\n<p><strong>Emily Alison<\/strong> <\/p>\n\n\n\n<p>Oui, je pense qu&rsquo;il s&rsquo;agit d&rsquo;un mouvement tr\u00e8s important. Et j&rsquo;ai vraiment l&rsquo;impression que nous sommes \u00e0 ce point de bascule autour de la pratique de l&rsquo;entretien au niveau mondial. En effet, nous sommes davantage conscients de ce qui se passe dans les diff\u00e9rentes parties du monde. J&rsquo;y inclus l&rsquo;Am\u00e9rique du Nord et l&rsquo;utilisation de m\u00e9thodes plus accusatrices, coercitives ou trompeuses. Je suis s\u00fbr que vous \u00eates au courant de la l\u00e9gislation qui balaie actuellement les \u00c9tats-Unis et qui interdit le recours \u00e0 la tromperie lors d&rsquo;entretiens avec des mineurs. Je veux dire que cela ressemble \u00e0 peine \u00e0 une phrase que vous devriez prononcer, \u00e0 savoir que la police ne devrait pas \u00eatre autoris\u00e9e \u00e0 mentir \u00e0 des enfants lors d&rsquo;un interrogatoire. Et pourtant, c&rsquo;est quelque chose&#8230; Parce que l&rsquo;un de vos principes \u00e9tait d&rsquo;\u00eatre honn\u00eate.         <\/p>\n\n\n\n<p><strong>B\u00f8rge Hansen<\/strong> <\/p>\n\n\n\n<p>La l\u00e9gislation vous permet donc de rompre le lien avec le suspect ou le t\u00e9moin.  <\/p>\n\n\n\n<p><strong>Emily Alison<\/strong> <\/p>\n\n\n\n<p>Tout \u00e0 fait. Et \u00e0 un niveau extr\u00eame, en insinuant des incoh\u00e9rences dans leur r\u00e9cit qui ne sont pas \u00e9tay\u00e9es par des preuves, en insinuant que les preuves existent, vous savez, ou en renfor\u00e7ant les preuves alors qu&rsquo;elles n&rsquo;existent pas, vous savez, en voyant votre ADN sur les lieux et des choses comme \u00e7a, alors qu&rsquo;elles n&rsquo;existent pas, je veux dire que vous ne devriez pas vraiment le faire, nous dirions, et m\u00eame globalement, qu&rsquo;il y a beaucoup de preuves pour dire que vous n&rsquo;avez pas besoin de faire cela du tout pour obtenir des informations et en fait, la diff\u00e9rence fondamentale, Je pense que la diff\u00e9rence fondamentale, et que les principes de Mendes apportent, est cette suppression des tactiques de pression externe. Le but d&rsquo;un entretien d&rsquo;investigation est d&rsquo;enqu\u00eater. Il ne s&rsquo;agit donc pas pour moi de chercher \u00e0 obtenir des aveux. L&rsquo;objectif est d&rsquo;obtenir des informations et un compte rendu que je pourrai ensuite confronter aux preuves. Que vous me mentiez ou non, cela m&rsquo;est \u00e9gal. Je testerai ce que vous direz \u00e0 la lumi\u00e8re des preuves dont je dispose. Et c&rsquo;est bien l\u00e0 la d\u00e9finition de l&rsquo;enqu\u00eate. Et pourtant, je pense qu&rsquo;il y a ce probl\u00e8me o\u00f9, dans les m\u00e9thodes plus accusatoires, il y a ces tactiques de pression externe qui sont utilis\u00e9es pour essayer d&rsquo;obtenir des aveux. Pour moi, c&rsquo;est l\u00e0 que r\u00e9side le probl\u00e8me. Je veux dire que c&rsquo;est la question fondamentale. Vous m&rsquo;avez donc demand\u00e9 quelle \u00e9tait la place d&rsquo;Orbit dans ce cadre.             <\/p>\n\n\n\n<p><strong>B\u00f8rge Hansen<\/strong> <\/p>\n\n\n\n<p>Je suis d\u00e9sol\u00e9, mais vous savez, je pense, et c&rsquo;est mon exp\u00e9rience personnelle, je pense que nous, en tant qu&rsquo;humains, vous savez, nous sommes biais\u00e9s et puis nous, quand nous, vous savez, pensons qu&rsquo;un et un s&rsquo;additionnent pour devenir deux, nous nous lan\u00e7ons dans l&rsquo;aventure. C&rsquo;est ainsi que, lorsque vous parlez de m\u00e9thodes accusatoires, vous dites en quelque sorte : \u00ab\u00a0Je crois que vous \u00eates coupable et je cherche \u00e0 le prouver\u00a0\u00bb. C&rsquo;est une m\u00e9thode intuitive pour nous, les humains, parce que voir c&rsquo;est croire et que nous avons des pr\u00e9jug\u00e9s, et vous savez, c&rsquo;est intuitif. Ce que vous faites, vous le savez, c&rsquo;est travailler sur l&rsquo;imagerie d&rsquo;investigation qui est plus, d&rsquo;une certaine mani\u00e8re, contre-intuitive.     <\/p>\n\n\n\n<p><strong>Emily Alison<\/strong> <\/p>\n\n\n\n<p>D&rsquo;une certaine mani\u00e8re, vous n&rsquo;\u00eates pas autoris\u00e9 \u00e0 prendre une d\u00e9cision tant que vous ne savez pas, tant que vous ne savez pas vraiment, tant qu&rsquo;il n&rsquo;y a pas d&rsquo;autre alternative. Et parfois, vous n&rsquo;atteindrez pas ce niveau. C&rsquo;est une question d&rsquo;\u00e9quilibre des preuves. Si vous \u00eates objectif et que vous partez d&rsquo;une position de curiosit\u00e9 plut\u00f4t que de suspicion, vous devriez \u00eatre en mesure de suspendre ce pr\u00e9jug\u00e9 ou du moins d&rsquo;essayer de l&rsquo;att\u00e9nuer. Car vous avez raison. Vous savez, c&rsquo;est souvent inconscient. Vous ne pouvez pas vous emp\u00eacher de penser ce que vous pensez de la situation, mais nous essayons de mettre en place des principes qui contrent ce pr\u00e9jug\u00e9 naturel et vous donnent une certaine objectivit\u00e9 pour op\u00e9rer, parce que nous connaissons d&rsquo;innombrables cas o\u00f9 vous pourriez demander \u00e0 100 personnes d&rsquo;examiner la situation et 98 % d&rsquo;entre elles diraient : \u00ab\u00a0Je sais ce qui s&rsquo;est pass\u00e9 ici\u00a0\u00bb. Or, ce n&rsquo;est pas exact. Ce n&rsquo;est pas la v\u00e9rit\u00e9. En fait, nous venons juste de nous rendre en Californie pour faire de la formation et pr\u00e9senter un symposium sur la pratique des entretiens.           <\/p>\n\n\n\n<p>Au m\u00eame symposium se trouvait le couple impliqu\u00e9 dans l&rsquo;affaire American nightmare, qui, comme vous le savez, est tr\u00e8s populaire sur Netflix. C&rsquo;est charg\u00e9. Les gens l&rsquo;ont regard\u00e9. Mais je pense que vous pourriez montrer ce cas \u00e0 une centaine de personnes et qu&rsquo;elles se diraient : \u00ab\u00a0Je, vous savez, cela me semble suspect\u00a0\u00bb. Je ne pense pas que ce soit vrai. Mais au lieu d&rsquo;agir sur ce qui se passe ici, les enqu\u00eateurs ont d\u00e9cid\u00e9.      <\/p>\n\n\n\n<p>Je sais ce qui s&rsquo;est pass\u00e9. Je suis certain \u00e0 100 % de ce qui s&rsquo;est pass\u00e9 et je vais poursuivre dans cette voie, \u00e0 l&rsquo;exclusion de toute autre explication potentielle. Et les cons\u00e9quences ont \u00e9t\u00e9 catastrophiques et d\u00e9chirantes. Je pense donc que pour moi, c&rsquo;est cela, et pour \u00eatre juste, ce n&rsquo;est pas leur \u00e9tat d&rsquo;esprit naturel. C&rsquo;est en fait un \u00e9tat d&rsquo;esprit qui leur a \u00e9t\u00e9 inculqu\u00e9 pour qu&rsquo;ils d\u00e9cident et poursuivent, pour qu&rsquo;ils poursuivent cette narration, cette confession, vous savez, elle est litt\u00e9ralement int\u00e9gr\u00e9e dans le syst\u00e8me, mais elle n&rsquo;est pas \u00e9tay\u00e9e par la science. Pour nous, cela fait partie de l&rsquo;orbite. Vous m&rsquo;avez demand\u00e9 quelle \u00e9tait la place de l&rsquo;orbite dans tout cela. Pour moi, c&rsquo;est qu&rsquo;elle apporte un cadre aux enqu\u00eateurs. Si nous disons qu&rsquo;il faut cesser d&rsquo;utiliser cette m\u00e9thode qui repose sur des aveux, qui est biais\u00e9e, qui est guid\u00e9e par la suspicion et le biais de confirmation plut\u00f4t que par la science, alors qu&rsquo;allons-nous faire \u00e0 la place ? Qu&rsquo;allons-nous faire \u00e0 la place si nous vous enlevons cela, et je suis d&rsquo;accord, vous savez, les principes de Mendes sont une plateforme importante pour dire que ce sont les principes de fonctionnement. Mais les enqu\u00eateurs diront : \u00ab\u00a0Comment suis-je cens\u00e9 entrer l\u00e0-dedans ? Comment suis-je cens\u00e9 obtenir ce que vous dites que je suis l\u00e0 pour obtenir, ils ne me diront rien. Ce que nous avons d\u00e9montr\u00e9 avec Orbit, c&rsquo;est que l&rsquo;utilisation de ce type de strat\u00e9gies de communication g\u00e9n\u00e8re une pression interne. En d&rsquo;autres termes, si je n&rsquo;ai rien fait, je suis innocent et je suis interrog\u00e9 par la police.               <\/p>\n\n\n\n<p>Il se peut que je ressente naturellement une pression ext\u00e9rieure. Je pourrais me sentir intimid\u00e9 par cet environnement et avoir un peu peur, mais je ne ressentirai pas de pression interne parce que je n&rsquo;ai rien fait. Donc, \u00e0 l&rsquo;int\u00e9rieur, je ne vous dirai que ce que je peux dire parce que je ne l&rsquo;ai pas fait. En revanche, si je suis coupable, je peux ressentir la m\u00eame pression externe naturelle, mais les principes d&rsquo;Orbit tentent d&rsquo;att\u00e9nuer cette pression externe en cr\u00e9ant de l&rsquo;honn\u00eatet\u00e9 et de l&#8217;empathie.     <\/p>\n\n\n\n<p>Vous savez, toutes ces sortes de principes. Au lieu de cela, il g\u00e9n\u00e8re une pression interne qui fait que j&rsquo;ai beaucoup de mal \u00e0 continuer \u00e0 \u00eatre trompeur ou \u00e0 dissimuler la v\u00e9rit\u00e9 r\u00e9elle de ce qui s&rsquo;est pass\u00e9. C&rsquo;est ainsi que les choses devraient se passer. Je ne vous dis pas quelque chose parce que vous avez fait pression sur moi. Je vous le dis parce que je ressens une pression interne telle que je me sens oblig\u00e9 de m&rsquo;expliquer. C&rsquo;est la raison pour laquelle quelqu&rsquo;un se confesse, et non pas parce que vous l&rsquo;avez forc\u00e9 \u00e0 le faire.      <\/p>\n\n\n\n<p><strong>B\u00f8rge Hansen<\/strong> <\/p>\n\n\n\n<p>Diriez-vous qu&rsquo;Orbit est une m\u00e9thode scientifique d&rsquo;\u00e9tablissement de rapports, mais qu&rsquo;il s&rsquo;agit aussi d&rsquo;enqu\u00eates. Vous devez en quelque sorte vous lib\u00e9rer de vos propres pr\u00e9jug\u00e9s, puis examiner l&rsquo;affaire sous diff\u00e9rents angles et faire preuve d&rsquo;ouverture d&rsquo;esprit \u00e0 l&rsquo;\u00e9gard de tout. S&rsquo;agit-il d&rsquo;une approche scientifique pour les entretiens dans leur ensemble ? Pensez-vous que c&rsquo;est la solution ? Je pense que oui.      <\/p>\n\n\n\n<p><strong>Emily Alison<\/strong> <\/p>\n\n\n\n<p>Je dirais qu&rsquo;il ne s&rsquo;agit pas d&rsquo;un mod\u00e8le de structure d&rsquo;entretien comme, vous savez, une sorte de pi\u00e8ce ou de cadre, qui divise les morceaux d&rsquo;un entretien, les diff\u00e9rentes phases d&rsquo;un entretien. En fait, ce que nous avons dit, c&rsquo;est que le rapport \u00e9tait souvent st\u00e9r\u00e9otyp\u00e9 comme \u00e9tant ce que vous faites au d\u00e9but. Vous savez, je vous demande comment vous avez dormi, je vous demande si vous voulez une tasse de th\u00e9, et c&rsquo;est une vision tellement simpliste du rapport. Ce n&rsquo;est pas de cela que nous parlons lorsque nous parlons de rapport. Il s&rsquo;agit d&rsquo;\u00e9tablir une v\u00e9ritable confiance et une connexion avec l&rsquo;autre personne. Et cela s&rsquo;applique \u00e0 toutes les \u00e9tapes de l&rsquo;entretien. Qu&rsquo;il s&rsquo;agisse de l&rsquo;ouverture d&rsquo;un compte ou de la pr\u00e9sentation de preuves \u00e0 un individu, nous avons dit que le rapport est toujours un facteur d\u00e9terminant de l&rsquo;entretien. En fait, dans la plupart des domaines offensifs dans lesquels nous travaillons, il ne s&rsquo;agit pas seulement de l&rsquo;infraction en face de vous. Il peut s&rsquo;agir de tous les autres comportements dans lesquels cet individu est impliqu\u00e9, qu&rsquo;il s&rsquo;agisse de terrorisme, d&rsquo;images ind\u00e9centes, de r\u00e9seaux de d\u00e9linquants, etc. C&rsquo;est pourquoi, lorsque nous formons des officiers de police, mon attitude consiste \u00e0 leur dire : \u00ab\u00a0Voulez-vous qu&rsquo;ils soient l\u00e0 pour la chose que vous avez devant vous ? Ou les voulez-vous pour tout ce dans quoi ils sont impliqu\u00e9s ? Et c&rsquo;est ce que nous visons. Et si c&rsquo;est ce que vous voulez, alors vous ne pouvez pas br\u00fbler le pont du rapport. Vous n&rsquo;avez pas le droit de faire le coup d&rsquo;Hollywood et de vous faire avoir, m\u00eame si c&rsquo;est psychologiquement satisfaisant pour l&rsquo;enqu\u00eateur. Vous ne pouvez tout simplement pas vivre ce moment.                <\/p>\n\n\n\n<p>Vous savez, vous pouvez l&rsquo;avoir \u00e0 l&rsquo;ext\u00e9rieur de la pi\u00e8ce, mais vous ne pouvez pas l&rsquo;avoir dans la pi\u00e8ce.  <\/p>\n\n\n\n<p><strong>B\u00f8rge Hansen<\/strong> <\/p>\n\n\n\n<p>Vous avez parl\u00e9 tout \u00e0 l&rsquo;heure des m\u00e9thodes accusatoires, puis des principes de Mendez. Quels sont les changements culturels que vous observez actuellement dans le monde ? Je sais que vous formez en Europe, mais vous formez aussi aux \u00c9tats-Unis et probablement ailleurs dans le monde. Comment voyez-vous le monde changer aujourd&rsquo;hui ?     <\/p>\n\n\n\n<p>Et o\u00f9 voyez-vous ce type de techniques ? Ou y a-t-il des environnements o\u00f9 les gens ont plus de mal avec cela parce qu&rsquo;ils se forment davantage \u00e0 d&rsquo;autres m\u00e9thodes de travail ?   <\/p>\n\n\n\n<p><strong>Emily Alison<\/strong> <\/p>\n\n\n\n<p>Oui, je pense, je veux dire, je l&rsquo;ai en quelque sorte d\u00e9crit comme un point de basculement. Et cela signifie en quelque sorte que nous sommes au sommet de la vague. La situation est donc assez moussante. On assiste un peu \u00e0 une bataille de petits pains \u00e0 l&rsquo;\u00e9chelle mondiale entre ces diff\u00e9rentes approches. J&rsquo;ai l&rsquo;impression que c&rsquo;est naturel. Cependant, vous savez, ce que j&rsquo;esp\u00e8re et ce \u00e0 quoi j&rsquo;aspire, c&rsquo;est que la science gagne, c&rsquo;est-\u00e0-dire que je comprends qu&rsquo;il y ait une certaine r\u00e9ticence \u00e0 abandonner des techniques ou des m\u00e9thodes utilis\u00e9es depuis longtemps et dont les gens pensent qu&rsquo;elles ont fonctionn\u00e9 pour eux. Et vous savez, c&rsquo;est tr\u00e8s, c&rsquo;est, vous devez accepter des m\u00e9thodes accusatrices ou coercitives alors qu&rsquo;elles, vous savez, nous entendons cela et savons que cela court le risque de faux aveux. Cela a \u00e9galement permis d&rsquo;obtenir de nombreux aveux authentiques de la part de personnes. Les gens se sentent donc renforc\u00e9s par cela et pensent que c&rsquo;est, eh bien, que cela a fonctionn\u00e9. Mais pour moi, il s&rsquo;agit d&rsquo;aider les gens \u00e0 dire, vous savez, \u00e0 accepter cette avanc\u00e9e, \u00e0 accepter ce que les connaissances nous disent, vous savez, \u00e0 changer au fur et \u00e0 mesure que la base de connaissances \u00e9volue. Et c&rsquo;est ce que vous feriez dans n&rsquo;importe quelle forme de police. Qu&rsquo;il s&rsquo;agisse de l&rsquo;analyse m\u00e9dico-l\u00e9gale num\u00e9rique, de l&rsquo;analyse des \u00e9claboussures de sang ou de la technologie de l&rsquo;ADN, la pratique a \u00e9volu\u00e9 au fur et \u00e0 mesure que ces outils devenaient de plus en plus avanc\u00e9s et perfectionn\u00e9s. Pourquoi ne ferions-nous pas de m\u00eame avec les Interviews ? Nous en savons beaucoup trop sur la mani\u00e8re de faire ce travail correctement et efficacement pour continuer \u00e0 pr\u00e9tendre que nous devons nous contenter d&rsquo;improviser sur la base de ce que quelqu&rsquo;un fait depuis 20 ans. Il y a suffisamment de donn\u00e9es scientifiques pour nous orienter dans la bonne direction, je pense.                <\/p>\n\n\n\n<p><strong>B\u00f8rge Hansen<\/strong> <\/p>\n\n\n\n<p>Alors comment faire si un homme, un policier enqu\u00eateur, je veux dire, ou m\u00eame un parent comprend, d&rsquo;accord, je ne m&rsquo;y prends pas de la bonne fa\u00e7on. Je suis curieux d&rsquo;en savoir plus sur cette m\u00e9thode scientifique qui a fait ses preuves et qui permet d&rsquo;\u00e9tablir un bon rapport et de mieux enqu\u00eater. Comment dois-je m&rsquo;y prendre ? Quel est votre conseil pour commencer ? Les gens sont curieux.      <\/p>\n\n\n\n<p><strong>Emily Alison<\/strong> <\/p>\n\n\n\n<p>Comme je l&rsquo;ai dit, cela fait partie de la conscience de soi. Il s&rsquo;agit de comprendre les principes de mani\u00e8re objective. Pour moi, l&rsquo;essentiel est que les impulsions \u00e9motionnelles soient out of. Vous avez toujours le droit d&rsquo;avoir ces \u00e9motions, mais elles ne vous aideront peut-\u00eatre pas \u00e0 atteindre votre objectif. Par exemple, si vous voulez que votre adolescent, je veux dire que la p\u00e9riode actuelle a \u00e9t\u00e9 horrible pour les jeunes, l&rsquo;apr\u00e8s-pand\u00e9mie les a fait se sentir tr\u00e8s isol\u00e9s, \u00e9vitants. Si vous voulez encourager votre enfant \u00e0 sortir, \u00e0 embrasser le monde, \u00e0 aller \u00e0 l&rsquo;universit\u00e9 ou autre, vous devez avoir cette conversation en essayant de le comprendre, et pas seulement en lui donnant des ordres et en lui disant ce qu&rsquo;il doit faire. Pour cela, vous devez \u00eatre pr\u00eat \u00e0 travailler et \u00e0 faire preuve de patience pour proc\u00e9der de cette mani\u00e8re, en comprenant que cela vous permettra d&rsquo;\u00e9tablir une connexion \u00e0 long terme, un lien, une confiance entre vous et votre enfant ou vous et la personne avec laquelle vous essayez d&rsquo;\u00e9tablir cette relation. Et cela demande beaucoup d&rsquo;efforts. Je pense donc qu&rsquo;il est bon de commencer par se demander qui m&rsquo;int\u00e9resse suffisamment pour que je veuille faire ce travail. \u00catre capable de le faire de cette mani\u00e8re, parce que c&rsquo;est un effort et qu&rsquo;il y aura des faux pas. Je veux dire que Lawrence et moi faisons cela depuis 20 ans et nous nous trompons encore r\u00e9guli\u00e8rement et nous nous disons l&rsquo;un \u00e0 l&rsquo;autre quand nous nous trompons. Je pense donc que si vous essayez de faire ce qu&rsquo;il faut et de le faire de la bonne mani\u00e8re autant que possible, vous serez \u00e0 l&rsquo;abri de ces exc\u00e8s. Et c&rsquo;est l\u00e0 mon principal objectif. Pour les personnes qui l&rsquo;utilisent \u00e0 titre individuel, c&rsquo;est tr\u00e8s bien. Pour les personnes qui l&rsquo;utilisent \u00e0 des fins professionnelles, vous devez disposer d&rsquo;un syst\u00e8me ou d&rsquo;une organisation qui vous aide \u00e0 faire les choses de la bonne mani\u00e8re, et non pas qui vous apprend \u00e0 faire les choses de la mauvaise mani\u00e8re, et vous devez ensuite les surmonter ou les d\u00e9faire.                <\/p>\n\n\n\n<p><strong>B\u00f8rge Hansen<\/strong> <\/p>\n\n\n\n<p>Il est bon d&rsquo;entendre que vous \u00eates aussi des \u00eatres humains et que vous pouvez vous en passer parce que je sais que c&rsquo;est un travail difficile d&rsquo;apprendre cela et que vous ferez des erreurs ici et l\u00e0. Et puis, comme vous le dites, avec la bonne formation et le bon environnement, vous pouvez apprendre de vos erreurs et vous am\u00e9liorer. Quelle est la prochaine \u00e9tape pour les Alison ? Qu&rsquo;est-ce qu&rsquo;il y a de neuf ?     <\/p>\n\n\n\n<p><strong>Emily Alison<\/strong> <\/p>\n\n\n\n<p>Je pense que nous n&rsquo;avons pas eu de vraies vacances depuis environ cinq ans, alors c&rsquo;est peut-\u00eatre \u00e7a.  <\/p>\n\n\n\n<p>Mais cela ne semble pas pr\u00e8s de se produire. Je pense qu&rsquo;en ce qui nous concerne, nous nous attaquons \u00e0 un certain nombre de choses, en particulier \u00e0 ces m\u00e9thodes accusatoires utilis\u00e9es principalement en Am\u00e9rique du Nord, mais aussi ailleurs dans le monde. Et nous avons l&rsquo;impression que, sans m\u00eame essayer, nous nous sommes retrouv\u00e9s au carr\u00e9 dans ce combat. Il est important pour moi, en tant que citoyen du monde, mais aussi des \u00c9tats-Unis de naissance, d&rsquo;essayer de promouvoir ce changement positif. Je pense que cela me fait mal de voir, c&rsquo;est ce que j&rsquo;ai dit lors de cette conf\u00e9rence en Californie. J&rsquo;ai dit, s&rsquo;il vous pla\u00eet, ne vous m\u00e9prenez pas sur le fait que nous voulons que vous fassiez ceci ou que vous changiez votre style \u00e0 cause de la personne qui se trouve en face de vous.      <\/p>\n\n\n\n<p>C&rsquo;est important pour la mani\u00e8re dont vous traitez une personne qui est sous votre garde. Mais souvent, la personne qui se trouve en face de ces gens a fait des choses horribles, des choses horribles \u00e0 d&rsquo;autres \u00eatres humains. Vous ne devriez certainement pas vous r\u00e9duire, vous compromettre, vous affaiblir pour un travail o\u00f9 vous essayez de faire ce qui est juste, vous savez, de voir la justice rendue, d&rsquo;\u00eatre le h\u00e9ros, et tout d&rsquo;un coup, cela vous transforme en m\u00e9chant. Pour moi, c&rsquo;est donc un peu une mission. Je crois que j&rsquo;ai dit apr\u00e8s cela que j&rsquo;avais l&rsquo;impression qu&rsquo;au cours des 20 derni\u00e8res ann\u00e9es, nous nous sommes peut-\u00eatre battus contre des moulins \u00e0 vent. Eh bien, nous sommes sur le point de faire exploser le moulin \u00e0 vent. Je suis donc assez optimiste \u00e0 ce sujet.        <\/p>\n\n\n\n<p><strong>B\u00f8rge Hansen<\/strong> <\/p>\n\n\n\n<p>C&rsquo;est vraiment g\u00e9nial. Je vous souhaite \u00e0 tous et \u00e0 nous-m\u00eames bonne chance en Europe et je vous soutiens dans la mission qui est la v\u00f4tre. Je pense que c&rsquo;est la bonne mission. Je pense que nous vous encourageons tous et que nous vous soutenons jusqu&rsquo;au bout. Merci, Emily, d&rsquo;avoir particip\u00e9 \u00e0 ce podcast et bonne chance.      <\/p>\n\n\n\n<p><strong>Emily Alison<\/strong> <\/p>\n\n\n\n<p>Je vous remercie de votre attention. Il en va de m\u00eame pour vous, B\u00f8rge. Je vous remercie de votre attention.    <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button read-more-btn\"><a class=\"wp-block-button__link wp-element-button\">En savoir plus<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-6c531013 wp-block-group-is-layout-flex\"><\/div>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Emily Alison, chercheur associ\u00e9, auteur et psychologue \u00e0 l&rsquo;Universit\u00e9 de Liverpool, discute de la m\u00e9thode Orbit&#8230;<\/p>\n","protected":false},"featured_media":4534,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"content-type-taxonomy":[73],"industry-taxonomy":[75,79],"class_list":["post-3579","resource-hub","type-resource-hub","status-publish","has-post-thumbnail","hentry","content-type-taxonomy-podcasts-fr","industry-taxonomy-military-fr","industry-taxonomy-policing-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Davidhorn<\/title>\n<meta name=\"description\" content=\"Ecoutez la psychologue Emily Alison sur les Interviews d&#039;Investigation couvrant la m\u00e9thode Orbit, l&#039;\u00e9tablissement de la confiance et les pratiques \u00e9thiques modernes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/davidhorn.com\/fr\/resource-hub\/beyond-a-reasonable-doubt-episode-03\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interviews d&#039;investigation Emily Alison - ep.03\" \/>\n<meta property=\"og:description\" content=\"Ecoutez la psychologue Emily Alison sur les Interviews d&#039;Investigation couvrant la m\u00e9thode Orbit, l&#039;\u00e9tablissement de la confiance et les pratiques \u00e9thiques modernes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/davidhorn.com\/fr\/resource-hub\/beyond-a-reasonable-doubt-episode-03\/\" \/>\n<meta property=\"og:site_name\" content=\"Davidhorn\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Equipped.for.Justice\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-25T13:09:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/d3pwq9e4hibwhv.cloudfront.net\/wp-content\/uploads\/2024\/07\/09095103\/11.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps de lecture estim\u00e9 \" \/>\n\t<meta name=\"twitter:data1\" content=\"36 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/davidhorn.com\\\/fr\\\/resource-hub\\\/beyond-a-reasonable-doubt-episode-03\\\/\",\"url\":\"https:\\\/\\\/davidhorn.com\\\/fr\\\/resource-hub\\\/beyond-a-reasonable-doubt-episode-03\\\/\",\"name\":\"Interviews d'investigation Emily Alison - ep.03 - Davidhorn\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/davidhorn.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/davidhorn.com\\\/fr\\\/resource-hub\\\/beyond-a-reasonable-doubt-episode-03\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/davidhorn.com\\\/fr\\\/resource-hub\\\/beyond-a-reasonable-doubt-episode-03\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d3pwq9e4hibwhv.cloudfront.net\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/09095103\\\/11.jpg\",\"datePublished\":\"2024-07-22T05:09:12+00:00\",\"dateModified\":\"2025-11-25T13:09:31+00:00\",\"description\":\"Ecoutez la psychologue Emily Alison sur les Interviews d'Investigation couvrant la m\u00e9thode Orbit, l'\u00e9tablissement de la confiance et les pratiques \u00e9thiques modernes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/davidhorn.com\\\/fr\\\/resource-hub\\\/beyond-a-reasonable-doubt-episode-03\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/davidhorn.com\\\/fr\\\/resource-hub\\\/beyond-a-reasonable-doubt-episode-03\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/davidhorn.com\\\/fr\\\/resource-hub\\\/beyond-a-reasonable-doubt-episode-03\\\/#primaryimage\",\"url\":\"https:\\\/\\\/d3pwq9e4hibwhv.cloudfront.net\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/09095103\\\/11.jpg\",\"contentUrl\":\"https:\\\/\\\/d3pwq9e4hibwhv.cloudfront.net\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/09095103\\\/11.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/davidhorn.com\\\/fr\\\/resource-hub\\\/beyond-a-reasonable-doubt-episode-03\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/davidhorn.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Podcasts\",\"item\":\"https:\\\/\\\/davidhorn.com\\\/fr\\\/content-type-taxonomy\\\/podcasts-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Interviews d&#8217;investigation Emily Alison &#8211; ep.03\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/davidhorn.com\\\/#website\",\"url\":\"https:\\\/\\\/davidhorn.com\\\/\",\"name\":\"Davidhorn\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/davidhorn.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/davidhorn.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/davidhorn.com\\\/#organization\",\"name\":\"Davidhorn\",\"url\":\"https:\\\/\\\/davidhorn.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/davidhorn.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d3pwq9e4hibwhv.cloudfront.net\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/29122828\\\/primary-1.svg\",\"contentUrl\":\"https:\\\/\\\/d3pwq9e4hibwhv.cloudfront.net\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/29122828\\\/primary-1.svg\",\"width\":200,\"height\":32,\"caption\":\"Davidhorn\"},\"image\":{\"@id\":\"https:\\\/\\\/davidhorn.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Equipped.for.Justice\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/davidhorn\",\"https:\\\/\\\/www.instagram.com\\\/davidhorn_company\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Davidhorn","description":"Ecoutez la psychologue Emily Alison sur les Interviews d'Investigation couvrant la m\u00e9thode Orbit, l'\u00e9tablissement de la confiance et les pratiques \u00e9thiques modernes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/davidhorn.com\/fr\/resource-hub\/beyond-a-reasonable-doubt-episode-03\/","og_locale":"fr_FR","og_type":"article","og_title":"Interviews d'investigation Emily Alison - ep.03","og_description":"Ecoutez la psychologue Emily Alison sur les Interviews d'Investigation couvrant la m\u00e9thode Orbit, l'\u00e9tablissement de la confiance et les pratiques \u00e9thiques modernes.","og_url":"https:\/\/davidhorn.com\/fr\/resource-hub\/beyond-a-reasonable-doubt-episode-03\/","og_site_name":"Davidhorn","article_publisher":"https:\/\/www.facebook.com\/Equipped.for.Justice\/","article_modified_time":"2025-11-25T13:09:31+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/d3pwq9e4hibwhv.cloudfront.net\/wp-content\/uploads\/2024\/07\/09095103\/11.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps de lecture estim\u00e9 ":"36 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/davidhorn.com\/fr\/resource-hub\/beyond-a-reasonable-doubt-episode-03\/","url":"https:\/\/davidhorn.com\/fr\/resource-hub\/beyond-a-reasonable-doubt-episode-03\/","name":"Interviews d'investigation Emily Alison - ep.03 - Davidhorn","isPartOf":{"@id":"https:\/\/davidhorn.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/davidhorn.com\/fr\/resource-hub\/beyond-a-reasonable-doubt-episode-03\/#primaryimage"},"image":{"@id":"https:\/\/davidhorn.com\/fr\/resource-hub\/beyond-a-reasonable-doubt-episode-03\/#primaryimage"},"thumbnailUrl":"https:\/\/d3pwq9e4hibwhv.cloudfront.net\/wp-content\/uploads\/2024\/07\/09095103\/11.jpg","datePublished":"2024-07-22T05:09:12+00:00","dateModified":"2025-11-25T13:09:31+00:00","description":"Ecoutez la psychologue Emily Alison sur les Interviews d'Investigation couvrant la m\u00e9thode Orbit, l'\u00e9tablissement de la confiance et les pratiques \u00e9thiques modernes.","breadcrumb":{"@id":"https:\/\/davidhorn.com\/fr\/resource-hub\/beyond-a-reasonable-doubt-episode-03\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/davidhorn.com\/fr\/resource-hub\/beyond-a-reasonable-doubt-episode-03\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/davidhorn.com\/fr\/resource-hub\/beyond-a-reasonable-doubt-episode-03\/#primaryimage","url":"https:\/\/d3pwq9e4hibwhv.cloudfront.net\/wp-content\/uploads\/2024\/07\/09095103\/11.jpg","contentUrl":"https:\/\/d3pwq9e4hibwhv.cloudfront.net\/wp-content\/uploads\/2024\/07\/09095103\/11.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/davidhorn.com\/fr\/resource-hub\/beyond-a-reasonable-doubt-episode-03\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/davidhorn.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Podcasts","item":"https:\/\/davidhorn.com\/fr\/content-type-taxonomy\/podcasts-fr\/"},{"@type":"ListItem","position":3,"name":"Interviews d&#8217;investigation Emily Alison &#8211; ep.03"}]},{"@type":"WebSite","@id":"https:\/\/davidhorn.com\/#website","url":"https:\/\/davidhorn.com\/","name":"Davidhorn","description":"","publisher":{"@id":"https:\/\/davidhorn.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/davidhorn.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/davidhorn.com\/#organization","name":"Davidhorn","url":"https:\/\/davidhorn.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/davidhorn.com\/#\/schema\/logo\/image\/","url":"https:\/\/d3pwq9e4hibwhv.cloudfront.net\/wp-content\/uploads\/2024\/05\/29122828\/primary-1.svg","contentUrl":"https:\/\/d3pwq9e4hibwhv.cloudfront.net\/wp-content\/uploads\/2024\/05\/29122828\/primary-1.svg","width":200,"height":32,"caption":"Davidhorn"},"image":{"@id":"https:\/\/davidhorn.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Equipped.for.Justice\/","https:\/\/www.linkedin.com\/company\/davidhorn","https:\/\/www.instagram.com\/davidhorn_company"]}]}},"_links":{"self":[{"href":"https:\/\/davidhorn.com\/fr\/wp-json\/wp\/v2\/resource-hub\/3579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/davidhorn.com\/fr\/wp-json\/wp\/v2\/resource-hub"}],"about":[{"href":"https:\/\/davidhorn.com\/fr\/wp-json\/wp\/v2\/types\/resource-hub"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/davidhorn.com\/fr\/wp-json\/wp\/v2\/media\/4534"}],"wp:attachment":[{"href":"https:\/\/davidhorn.com\/fr\/wp-json\/wp\/v2\/media?parent=3579"}],"wp:term":[{"taxonomy":"content-type-taxonomy","embeddable":true,"href":"https:\/\/davidhorn.com\/fr\/wp-json\/wp\/v2\/content-type-taxonomy?post=3579"},{"taxonomy":"industry-taxonomy","embeddable":true,"href":"https:\/\/davidhorn.com\/fr\/wp-json\/wp\/v2\/industry-taxonomy?post=3579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}